{"id":12810,"date":"2017-01-16T09:15:12","date_gmt":"2017-01-16T07:15:12","guid":{"rendered":"http:\/\/epood.saara.ee\/en\/pood\/kanarbikupunane-8_2"},"modified":"2023-04-06T23:51:09","modified_gmt":"2023-04-06T20:51:09","slug":"heather-red-8-2","status":"publish","type":"product","link":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2","title":{"rendered":"Heather Red 8\/2"},"content":{"rendered":"<p>Traditional woolen yarn is produced in Estonia. It is GOOD for knitting traditional mittens and socks. Outcome will be beautiful, authentic and warm like old Estonian knits when you knit tightly.<\/p>\n<p>We recommend using needles number 1,25; 1,5; 1,75 or 2 (US 0000 to 0).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GOOD Yarn for mittens 8\/2 (Made in Estonia)<\/p>\n<div>100% wool<\/div>\n<div>Dimensions: 50g\/200m<\/div>\n<div>Color: Heather Red<\/div>\n","protected":false},"featured_media":12792,"template":"","meta":[],"product_brand":[],"product_cat":[177,203],"product_tag":[816,817,818,210,821,823,826],"class_list":{"0":"post-12810","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-yarns","7":"product_cat-estonian-yarn-8-2","8":"product_tag-100-vill-en","9":"product_tag-100-wool-en","10":"product_tag-8-2-en","11":"product_tag-eesti-long-en","12":"product_tag-glove-yarn-en","13":"product_tag-mitten-yarn-en","14":"product_tag-sock-yarn-en","16":"first","17":"outofstock","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heather Red 8\/2 - Saara Kirjastus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heather Red 8\/2 - Saara Kirjastus\" \/>\n<meta property=\"og:description\" content=\"GOOD Yarn for mittens 8\/2 (Made in Estonia) 100% wool Dimensions: 50g\/200m Color: Heather Red\" \/>\n<meta property=\"og:url\" content=\"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2\" \/>\n<meta property=\"og:site_name\" content=\"Saara Kirjastus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Saara-Kirjastus\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T20:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/epood.saara.ee\/wp-content\/uploads\/2017\/01\/kanarbikupunane-8_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2\",\"url\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2\",\"name\":\"Heather Red 8\\\/2 - Saara Kirjastus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/epood.saara.ee\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/kanarbikupunane-8_2.jpg\",\"datePublished\":\"2017-01-16T07:15:12+00:00\",\"dateModified\":\"2023-04-06T20:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2#primaryimage\",\"url\":\"https:\\\/\\\/epood.saara.ee\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/kanarbikupunane-8_2.jpg\",\"contentUrl\":\"https:\\\/\\\/epood.saara.ee\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/kanarbikupunane-8_2.jpg\",\"width\":600,\"height\":600,\"caption\":\"Heather Red Yarn 8\\\/2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/pood\\\/heather-red-8-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/epood.saara.ee\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/epood.saara.ee\\\/en\\\/shop\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Heather Red 8\\\/2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/#website\",\"url\":\"https:\\\/\\\/epood.saara.ee\\\/\",\"name\":\"Saara Kirjastus\",\"description\":\"Kujundusteenused, raamatud, k&auml;sit&ouml;&ouml;\",\"publisher\":{\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/epood.saara.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/#organization\",\"name\":\"Saarakiri O\u00dc\",\"url\":\"https:\\\/\\\/epood.saara.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/epood.saara.ee\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/saara_mv_R.png\",\"contentUrl\":\"https:\\\/\\\/epood.saara.ee\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/saara_mv_R.png\",\"width\":649,\"height\":226,\"caption\":\"Saarakiri O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/epood.saara.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Saara-Kirjastus\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heather Red 8\/2 - Saara Kirjastus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2","og_locale":"en_US","og_type":"article","og_title":"Heather Red 8\/2 - Saara Kirjastus","og_description":"GOOD Yarn for mittens 8\/2 (Made in Estonia) 100% wool Dimensions: 50g\/200m Color: Heather Red","og_url":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2","og_site_name":"Saara Kirjastus","article_publisher":"https:\/\/www.facebook.com\/Saara-Kirjastus","article_modified_time":"2023-04-06T20:51:09+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/epood.saara.ee\/wp-content\/uploads\/2017\/01\/kanarbikupunane-8_2.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2","url":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2","name":"Heather Red 8\/2 - Saara Kirjastus","isPartOf":{"@id":"https:\/\/epood.saara.ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2#primaryimage"},"image":{"@id":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2#primaryimage"},"thumbnailUrl":"https:\/\/epood.saara.ee\/wp-content\/uploads\/2017\/01\/kanarbikupunane-8_2.jpg","datePublished":"2017-01-16T07:15:12+00:00","dateModified":"2023-04-06T20:51:09+00:00","breadcrumb":{"@id":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2#primaryimage","url":"https:\/\/epood.saara.ee\/wp-content\/uploads\/2017\/01\/kanarbikupunane-8_2.jpg","contentUrl":"https:\/\/epood.saara.ee\/wp-content\/uploads\/2017\/01\/kanarbikupunane-8_2.jpg","width":600,"height":600,"caption":"Heather Red Yarn 8\/2"},{"@type":"BreadcrumbList","@id":"https:\/\/epood.saara.ee\/en\/pood\/heather-red-8-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/epood.saara.ee\/en"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/epood.saara.ee\/en\/shop"},{"@type":"ListItem","position":3,"name":"Heather Red 8\/2"}]},{"@type":"WebSite","@id":"https:\/\/epood.saara.ee\/#website","url":"https:\/\/epood.saara.ee\/","name":"Saara Kirjastus","description":"Kujundusteenused, raamatud, k&auml;sit&ouml;&ouml;","publisher":{"@id":"https:\/\/epood.saara.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/epood.saara.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/epood.saara.ee\/#organization","name":"Saarakiri O\u00dc","url":"https:\/\/epood.saara.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/epood.saara.ee\/#\/schema\/logo\/image\/","url":"https:\/\/epood.saara.ee\/wp-content\/uploads\/2015\/03\/saara_mv_R.png","contentUrl":"https:\/\/epood.saara.ee\/wp-content\/uploads\/2015\/03\/saara_mv_R.png","width":649,"height":226,"caption":"Saarakiri O\u00dc"},"image":{"@id":"https:\/\/epood.saara.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Saara-Kirjastus"]}]}},"_links":{"self":[{"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/product\/12810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/media\/12792"}],"wp:attachment":[{"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/media?parent=12810"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/product_brand?post=12810"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/product_cat?post=12810"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/epood.saara.ee\/en\/wp-json\/wp\/v2\/product_tag?post=12810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}